{"id":59,"count":18,"description":"","link":"https:\/\/santeams.com\/en\/category\/medical-sos\/","name":"Medical SOS","slug":"medical-sos","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"z4zz1Wsod1Badct7CbT0I1NRuSpPyUGogeDUu1ZJMfU\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/santeams.com\/en\/category\/medical-sos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/59\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/santeams.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/category\\\/medical-sos\\\/#listItem\",\"name\":\"Medical SOS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/category\\\/medical-sos\\\/#listItem\",\"position\":2,\"name\":\"Medical SOS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/59\\\/#collectionpage\",\"url\":\"https:\\\/\\\/santeams.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/59\\\/\",\"name\":\"Medical SOS - EN AMS African medical supply\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/59\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/#organization\",\"name\":\"EN AMS African medical supply\",\"description\":\"Medical services by AMS offer Discover Medical SOS solutions and services for individuals in Guinea. Learn more about health. Welcome to AMS Management, dedicated to Comprehensive Diagnosis in Occupational Health &amp; Safety. Contact us at AMS: your reliable health and safety partner in Guinea. About us: AMS- Your Health &amp; Safety Partner, placing safety at the heart of healthcare.\",\"url\":\"https:\\\/\\\/santeams.com\\\/en\\\/\",\"telephone\":\"+224610723838\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/santeams.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/cropped-favicon.png\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/59\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/59\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/africanmedicalsupply\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/african-medical-supply\\\/?viewAsMember=true\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/santeams.com\\\/en\\\/\",\"name\":\"EN AMS African medical supply\",\"description\":\"Prestation de service m\\u00e9dical externalis\\u00e9 - AMS African medical supply\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/santeams.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Medical SOS - EN AMS African medical supply","description":"","canonical_url":"https:\/\/santeams.com\/en\/category\/medical-sos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"z4zz1Wsod1Badct7CbT0I1NRuSpPyUGogeDUu1ZJMfU","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories\/59\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/santeams.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/santeams.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/santeams.com\/en\/category\/medical-sos\/#listItem","name":"Medical SOS"}},{"@type":"ListItem","@id":"https:\/\/santeams.com\/en\/category\/medical-sos\/#listItem","position":2,"name":"Medical SOS","previousItem":{"@type":"ListItem","@id":"https:\/\/santeams.com\/en#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories\/59\/#collectionpage","url":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories\/59\/","name":"Medical SOS - EN AMS African medical supply","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/santeams.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories\/59\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/santeams.com\/en\/#organization","name":"EN AMS African medical supply","description":"Medical services by AMS offer Discover Medical SOS solutions and services for individuals in Guinea. Learn more about health. Welcome to AMS Management, dedicated to Comprehensive Diagnosis in Occupational Health &amp; Safety. Contact us at AMS: your reliable health and safety partner in Guinea. About us: AMS- Your Health &amp; Safety Partner, placing safety at the heart of healthcare.","url":"https:\/\/santeams.com\/en\/","telephone":"+224610723838","logo":{"@type":"ImageObject","url":"https:\/\/santeams.com\/en\/wp-content\/uploads\/sites\/2\/2025\/02\/cropped-favicon.png","@id":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories\/59\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories\/59\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/africanmedicalsupply","https:\/\/www.linkedin.com\/company\/african-medical-supply\/?viewAsMember=true"]},{"@type":"WebSite","@id":"https:\/\/santeams.com\/en\/#website","url":"https:\/\/santeams.com\/en\/","name":"EN AMS African medical supply","description":"Prestation de service m\u00e9dical externalis\u00e9 - AMS African medical supply","inLanguage":"en-US","publisher":{"@id":"https:\/\/santeams.com\/en\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/santeams.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMedical SOS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/santeams.com\/en"},{"label":"Medical SOS","link":"https:\/\/santeams.com\/en\/category\/medical-sos\/"}],"_links":{"self":[{"href":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/santeams.com\/en\/wp-json\/wp\/v2\/posts?categories=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}